{"id":113141,"date":"2024-07-05T12:24:25","date_gmt":"2024-07-05T10:24:25","guid":{"rendered":"https:\/\/www.ro-spain.com\/property\/geweldige-vrijstaande-villas-in-rojales-alicante\/"},"modified":"2026-04-22T16:24:23","modified_gmt":"2026-04-22T14:24:23","slug":"estupenda-villa-independiente-en-rojales-alicante","status":"publish","type":"property","link":"https:\/\/www.ro-spain.com\/es\/property\/estupenda-villa-independiente-en-rojales-alicante\/","title":{"rendered":"Estupenda villa independiente en Rojales, Alicante"},"content":{"rendered":"<div>Se distribuye en dos plantas con 3 dormitorios y 3 ba\u00f1os con dise\u00f1os modernos y elegantes.<\/div>\n<div>\n<div>\n<p>Cuenta con una sala de estar y comedor de planta abierta con mucha luz, una cocina totalmente amueblada con\u00a0armarios altos, bajos y fregadero\u00a0empotrado.<\/p>\n<\/div>\n<div>\n<p>En cuanto a los dormitorios son amplios con modernos armarios lacados en blanco.<\/p>\n<\/div>\n<div>\n<p>Los ba\u00f1os se entregan completos con lavabo, muebles de ba\u00f1o, espejo y mampara de ducha.La villa dispone de instalaci\u00f3n de aire acondicionado por conductos, agua caliente sanitaria, videoportero, persianas el\u00e9ctricas, iluminaci\u00f3n led en toda la casa y sistema dom\u00f3tico.<\/p>\n<\/div>\n<div>\n<p>En el espacio exterior se encuentra piscina privada con amplio jard\u00edn en parcela de 200m2 y parking privado.<\/p>\n<\/div>\n<div>\n<p>El proyecto se encuentra en Rojales es un hermoso pueblo en la Costa Blanca sur tiene unas inmejorables playas a 10 minutos, a pocos kil\u00f3metros de la ciudad de Alicante y Torrevieja y tan solo 35 minutos del aeropuerto de Alicante. Tambi\u00e9n cuenta con gran variedad de oferta de servicios, conexiones y ocio.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se distribuye en dos plantas con 3 dormitorios y 3 ba\u00f1os con dise\u00f1os modernos y elegantes. Cuenta con una sala de estar y comedor de planta abierta con mucha luz, una cocina totalmente amueblada con\u00a0armarios altos, bajos y fregadero\u00a0empotrado. En cuanto a los dormitorios son amplios con modernos armarios lacados en blanco. Los ba\u00f1os se&#8230;<\/p>\n","protected":false},"author":1,"featured_media":134702,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-feature":[269,276,505,254,255,256,258,261],"property-type":[249],"property-city":[647],"property-status":[260],"class_list":["post-113141","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-piscina-privada","property-feature-terraza-en-azotea","property-feature-solarium","property-feature-cocina-equipada","property-feature-jardin","property-feature-aparcamiento-privado","property-feature-terraza","property-feature-preinstalacion-aire-acondicionado","property-type-chalet","property-city-rojales-ciudad-quesada","property-status-nueva-construccion","zones-cz","builders-carmelo-y-partners"],"aioseo_notices":[],"property_meta":{"REAL_HOMES_property_price":"465000","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"","REAL_HOMES_property_size":"140","REAL_HOMES_property_size_postfix":"m2","REAL_HOMES_property_lot_size":"207","REAL_HOMES_property_lot_size_postfix":"m2","REAL_HOMES_property_bedrooms":"3","REAL_HOMES_property_bathrooms":"3","REAL_HOMES_property_garage":"","REAL_HOMES_property_id":"CZ26.05.113105","REAL_HOMES_property_year_built":"","rvr_property_owner":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"38.0860483","longitude":"-0.7235857","zoom":"14"},"REAL_HOMES_property_address":"03170 Rojales, Alicante, Espa\u00f1a","REAL_HOMES_property_map":"0","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1.png","filesize":8165589,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-300x181.png","width":300,"height":181,"mime-type":"image\/png","filesize":86313,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-300x181.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-1024x619.png","width":1024,"height":619,"mime-type":"image\/png","filesize":839002,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-1024x619.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":35463,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-768x464.png","width":768,"height":464,"mime-type":"image\/png","filesize":494382,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-768x464.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":24287,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-1536x929.png","width":1536,"height":929,"mime-type":"image\/png","filesize":1908131,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-1536x929.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-2048x1238.png","width":2048,"height":1238,"mime-type":"image\/png","filesize":3297369,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-2048x1238.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-150x91.png","width":150,"height":91,"mime-type":"image\/png","filesize":25503,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-150x91.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":461859,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":231087,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":484906,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":63693,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-600x1722.png","width":600,"height":1722,"mime-type":"image\/png","filesize":1470617,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-600x1722.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1196006,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":117960,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":200172,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":433622,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134758","name":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1.png","title":"Captura de pantalla 2026-02-16 a las 10.29.35","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15.png","filesize":8990656,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-300x199.png","width":300,"height":199,"mime-type":"image\/png","filesize":80347,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-300x199.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-1024x680.png","width":1024,"height":680,"mime-type":"image\/png","filesize":787212,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-1024x680.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":34511,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-768x510.png","width":768,"height":510,"mime-type":"image\/png","filesize":455365,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-768x510.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":23479,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-1536x1020.png","width":1536,"height":1020,"mime-type":"image\/png","filesize":1879948,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-1536x1020.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-2048x1360.png","width":2048,"height":1360,"mime-type":"image\/png","filesize":3628912,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-2048x1360.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-150x100.png","width":150,"height":100,"mime-type":"image\/png","filesize":24001,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-150x100.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":409669,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":188159,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":403292,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":61619,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-600x1760.png","width":600,"height":1760,"mime-type":"image\/png","filesize":1829598,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-600x1760.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1039861,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":114256,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":193702,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.15-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":426174,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134710","name":"Captura-de-pantalla-2026-02-16-a-las-10.30.15.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15.png","title":"Captura de pantalla 2026-02-16 a las 10.30.15","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.15-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08.png","filesize":5443949,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-300x200.png","width":300,"height":200,"mime-type":"image\/png","filesize":77077,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-300x200.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-1024x681.png","width":1024,"height":681,"mime-type":"image\/png","filesize":648521,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-1024x681.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":33034,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-768x511.png","width":768,"height":511,"mime-type":"image\/png","filesize":393233,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-768x511.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":22475,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-1536x1022.png","width":1536,"height":1022,"mime-type":"image\/png","filesize":1288867,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-1536x1022.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-2048x1363.png","width":2048,"height":1363,"mime-type":"image\/png","filesize":2053022,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-2048x1363.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-150x100.png","width":150,"height":100,"mime-type":"image\/png","filesize":23719,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-150x100.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":352981,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":178758,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":351643,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":58526,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-600x1742.png","width":600,"height":1742,"mime-type":"image\/png","filesize":609846,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-600x1742.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":804040,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":108992,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":180040,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.08-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":367410,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134746","name":"Captura-de-pantalla-2026-02-16-a-las-10.32.08.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08.png","title":"Captura de pantalla 2026-02-16 a las 10.32.08","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.08-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48.png","filesize":4196830,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-300x198.png","width":300,"height":198,"mime-type":"image\/png","filesize":73129,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-300x198.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-1024x676.png","width":1024,"height":676,"mime-type":"image\/png","filesize":586468,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-1024x676.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":30262,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-768x507.png","width":768,"height":507,"mime-type":"image\/png","filesize":365741,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-768x507.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":20688,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-1536x1015.png","width":1536,"height":1015,"mime-type":"image\/png","filesize":1140265,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-1536x1015.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-2048x1353.png","width":2048,"height":1353,"mime-type":"image\/png","filesize":1784819,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-2048x1353.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-150x99.png","width":150,"height":99,"mime-type":"image\/png","filesize":22166,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-150x99.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":326905,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":171591,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":321612,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":54246,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-600x1752.png","width":600,"height":1752,"mime-type":"image\/png","filesize":621245,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-600x1752.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":715393,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":99364,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":161989,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.48-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":316113,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134698","name":"Captura-de-pantalla-2026-02-16-a-las-10.29.48.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48.png","title":"Captura de pantalla 2026-02-16 a las 10.29.48","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.48-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16.png","filesize":4219547,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-300x199.png","width":300,"height":199,"mime-type":"image\/png","filesize":71849,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-300x199.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-1024x678.png","width":1024,"height":678,"mime-type":"image\/png","filesize":599149,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-1024x678.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":31179,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-768x509.png","width":768,"height":509,"mime-type":"image\/png","filesize":371037,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-768x509.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":20973,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-1536x1017.png","width":1536,"height":1017,"mime-type":"image\/png","filesize":1144387,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-1536x1017.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-2048x1356.png","width":2048,"height":1356,"mime-type":"image\/png","filesize":1779572,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-2048x1356.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-150x99.png","width":150,"height":99,"mime-type":"image\/png","filesize":20764,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-150x99.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":338295,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":170476,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":316956,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":56265,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-600x1734.png","width":600,"height":1734,"mime-type":"image\/png","filesize":842290,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-600x1734.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":720571,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":105219,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":173668,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.16-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":346259,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134750","name":"Captura-de-pantalla-2026-02-16-a-las-10.32.16.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16.png","title":"Captura de pantalla 2026-02-16 a las 10.32.16","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.16-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02.png","filesize":5538324,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-300x199.png","width":300,"height":199,"mime-type":"image\/png","filesize":76458,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-300x199.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-1024x679.png","width":1024,"height":679,"mime-type":"image\/png","filesize":696113,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-1024x679.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":33529,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-768x509.png","width":768,"height":509,"mime-type":"image\/png","filesize":412638,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-768x509.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":22831,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-1536x1019.png","width":1536,"height":1019,"mime-type":"image\/png","filesize":1461652,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-1536x1019.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-2048x1359.png","width":2048,"height":1359,"mime-type":"image\/png","filesize":2470050,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-2048x1359.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-150x100.png","width":150,"height":100,"mime-type":"image\/png","filesize":23313,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-150x100.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":373050,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":182652,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":367061,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":59514,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-600x1746.png","width":600,"height":1746,"mime-type":"image\/png","filesize":1099270,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-600x1746.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":872644,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":111474,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":185689,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.02-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":384019,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134730","name":"Captura-de-pantalla-2026-02-16-a-las-10.31.02.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02.png","title":"Captura de pantalla 2026-02-16 a las 10.31.02","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.02-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10.png","filesize":5646291,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-300x198.png","width":300,"height":198,"mime-type":"image\/png","filesize":69445,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-300x198.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-1024x677.png","width":1024,"height":677,"mime-type":"image\/png","filesize":649044,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-1024x677.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":31741,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-768x508.png","width":768,"height":508,"mime-type":"image\/png","filesize":381809,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-768x508.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":21804,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-1536x1015.png","width":1536,"height":1015,"mime-type":"image\/png","filesize":1396773,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-1536x1015.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-2048x1354.png","width":2048,"height":1354,"mime-type":"image\/png","filesize":2395930,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-2048x1354.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-150x99.png","width":150,"height":99,"mime-type":"image\/png","filesize":21083,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-150x99.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":353369,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":167514,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":318935,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":57071,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-600x1752.png","width":600,"height":1752,"mime-type":"image\/png","filesize":982367,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-600x1752.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":805247,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":107371,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":180109,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.10-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":382238,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134734","name":"Captura-de-pantalla-2026-02-16-a-las-10.31.10.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10.png","title":"Captura de pantalla 2026-02-16 a las 10.31.10","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.10-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31.png","filesize":5093932,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-300x197.png","width":300,"height":197,"mime-type":"image\/png","filesize":80216,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-300x197.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-1024x672.png","width":1024,"height":672,"mime-type":"image\/png","filesize":699774,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-1024x672.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":30612,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-768x504.png","width":768,"height":504,"mime-type":"image\/png","filesize":425211,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-768x504.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":20745,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-1536x1008.png","width":1536,"height":1008,"mime-type":"image\/png","filesize":1392814,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-1536x1008.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-2048x1344.png","width":2048,"height":1344,"mime-type":"image\/png","filesize":2231140,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-2048x1344.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-150x98.png","width":150,"height":98,"mime-type":"image\/png","filesize":23797,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-150x98.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":372809,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":193556,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":373753,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":54935,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-600x1742.png","width":600,"height":1742,"mime-type":"image\/png","filesize":581563,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-600x1742.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":862542,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":102244,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":168027,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.31-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":335015,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134718","name":"Captura-de-pantalla-2026-02-16-a-las-10.30.31.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31.png","title":"Captura de pantalla 2026-02-16 a las 10.30.31","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.31-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22.png","filesize":6061519,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-300x199.png","width":300,"height":199,"mime-type":"image\/png","filesize":76658,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-300x199.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-1024x679.png","width":1024,"height":679,"mime-type":"image\/png","filesize":746772,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-1024x679.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":31907,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-768x509.png","width":768,"height":509,"mime-type":"image\/png","filesize":433856,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-768x509.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":21455,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-1536x1018.png","width":1536,"height":1018,"mime-type":"image\/png","filesize":1600372,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-1536x1018.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-2048x1358.png","width":2048,"height":1358,"mime-type":"image\/png","filesize":2685550,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-2048x1358.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-150x99.png","width":150,"height":99,"mime-type":"image\/png","filesize":22503,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-150x99.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":389435,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":188024,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":382475,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":58264,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-600x1758.png","width":600,"height":1758,"mime-type":"image\/png","filesize":1121997,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-600x1758.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":949843,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":112287,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":190580,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.22-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":407409,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134714","name":"Captura-de-pantalla-2026-02-16-a-las-10.30.22.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22.png","title":"Captura de pantalla 2026-02-16 a las 10.30.22","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.22-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41.png","filesize":6645505,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-300x198.png","width":300,"height":198,"mime-type":"image\/png","filesize":88423,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-300x198.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-1024x677.png","width":1024,"height":677,"mime-type":"image\/png","filesize":859624,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-1024x677.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":37476,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-768x508.png","width":768,"height":508,"mime-type":"image\/png","filesize":504513,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-768x508.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":25118,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-1536x1016.png","width":1536,"height":1016,"mime-type":"image\/png","filesize":1839039,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-1536x1016.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-2048x1354.png","width":2048,"height":1354,"mime-type":"image\/png","filesize":3137905,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-2048x1354.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-150x99.png","width":150,"height":99,"mime-type":"image\/png","filesize":25550,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-150x99.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":463619,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":219090,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":437423,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":68856,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-600x1756.png","width":600,"height":1756,"mime-type":"image\/png","filesize":1406865,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-600x1756.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1080076,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":133149,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":227749,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.41-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":485983,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134722","name":"Captura-de-pantalla-2026-02-16-a-las-10.30.41.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41.png","title":"Captura de pantalla 2026-02-16 a las 10.30.41","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.41-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05.png","filesize":8945162,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-300x199.png","width":300,"height":199,"mime-type":"image\/png","filesize":115355,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-300x199.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-1024x678.png","width":1024,"height":678,"mime-type":"image\/png","filesize":1233859,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-1024x678.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":42318,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-768x509.png","width":768,"height":509,"mime-type":"image\/png","filesize":715678,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-768x509.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":27790,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-1536x1017.png","width":1536,"height":1017,"mime-type":"image\/png","filesize":2658301,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-1536x1017.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-2048x1356.png","width":2048,"height":1356,"mime-type":"image\/png","filesize":4541846,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-2048x1356.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-150x99.png","width":150,"height":99,"mime-type":"image\/png","filesize":29539,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-150x99.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":625661,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":300152,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":626257,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":80672,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-600x1764.png","width":600,"height":1764,"mime-type":"image\/png","filesize":1534040,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-600x1764.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1569467,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":160308,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":276702,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.05-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":597041,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134706","name":"Captura-de-pantalla-2026-02-16-a-las-10.30.05.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05.png","title":"Captura de pantalla 2026-02-16 a las 10.30.05","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.05-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54.png","filesize":6973634,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-300x199.png","width":300,"height":199,"mime-type":"image\/png","filesize":91160,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-300x199.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-1024x678.png","width":1024,"height":678,"mime-type":"image\/png","filesize":877714,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-1024x678.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":36747,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-768x509.png","width":768,"height":509,"mime-type":"image\/png","filesize":515326,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-768x509.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":24556,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-1536x1017.png","width":1536,"height":1017,"mime-type":"image\/png","filesize":1908232,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-1536x1017.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-2048x1356.png","width":2048,"height":1356,"mime-type":"image\/png","filesize":3304181,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-2048x1356.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-150x99.png","width":150,"height":99,"mime-type":"image\/png","filesize":25973,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-150x99.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":456246,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":220379,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":464014,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":67740,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-600x1756.png","width":600,"height":1756,"mime-type":"image\/png","filesize":1382822,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-600x1756.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1136178,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":126827,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":214796,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.30.54-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":458207,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134726","name":"Captura-de-pantalla-2026-02-16-a-las-10.30.54.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54.png","title":"Captura de pantalla 2026-02-16 a las 10.30.54","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.30.54-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25.png","filesize":6127263,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-300x167.png","width":300,"height":167,"mime-type":"image\/png","filesize":82472,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-300x167.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-1024x569.png","width":1024,"height":569,"mime-type":"image\/png","filesize":716811,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-1024x569.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":35691,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-768x427.png","width":768,"height":427,"mime-type":"image\/png","filesize":435712,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-768x427.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":23887,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-1536x853.png","width":1536,"height":853,"mime-type":"image\/png","filesize":1413326,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-1536x853.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-2048x1138.png","width":2048,"height":1138,"mime-type":"image\/png","filesize":2246866,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-2048x1138.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-150x83.png","width":150,"height":83,"mime-type":"image\/png","filesize":23688,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-150x83.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":425906,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":225114,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":441617,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":64732,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-600x1748.png","width":600,"height":1748,"mime-type":"image\/png","filesize":616736,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-600x1748.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1021932,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":121912,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":200546,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.32.25-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":402354,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134754","name":"Captura-de-pantalla-2026-02-16-a-las-10.32.25.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25.png","title":"Captura de pantalla 2026-02-16 a las 10.32.25","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.32.25-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35.png","filesize":8165589,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-300x181.png","width":300,"height":181,"mime-type":"image\/png","filesize":86313,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-300x181.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1024x619.png","width":1024,"height":619,"mime-type":"image\/png","filesize":839002,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1024x619.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":35463,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-768x464.png","width":768,"height":464,"mime-type":"image\/png","filesize":494382,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-768x464.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":24287,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1536x929.png","width":1536,"height":929,"mime-type":"image\/png","filesize":1908131,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1536x929.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-2048x1238.png","width":2048,"height":1238,"mime-type":"image\/png","filesize":3297369,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-2048x1238.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-150x91.png","width":150,"height":91,"mime-type":"image\/png","filesize":25503,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-150x91.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":461859,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":231087,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":484906,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":63693,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-600x1722.png","width":600,"height":1722,"mime-type":"image\/png","filesize":1470617,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-600x1722.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1196006,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":117960,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":200172,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.35-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":433622,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134694","name":"Captura-de-pantalla-2026-02-16-a-las-10.29.35.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35.png","title":"Captura de pantalla 2026-02-16 a las 10.29.35","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.35-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58.png","filesize":8008228,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-300x198.png","width":300,"height":198,"mime-type":"image\/png","filesize":106106,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-300x198.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-1024x676.png","width":1024,"height":676,"mime-type":"image\/png","filesize":1078800,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-1024x676.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":40606,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-768x507.png","width":768,"height":507,"mime-type":"image\/png","filesize":627235,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-768x507.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":27013,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-1536x1014.png","width":1536,"height":1014,"mime-type":"image\/png","filesize":2322216,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-1536x1014.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-2048x1352.png","width":2048,"height":1352,"mime-type":"image\/png","filesize":3970544,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-2048x1352.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-150x99.png","width":150,"height":99,"mime-type":"image\/png","filesize":29750,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-150x99.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":554175,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":266584,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":554141,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":75922,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-600x1754.png","width":600,"height":1754,"mime-type":"image\/png","filesize":1720791,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-600x1754.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1390878,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":148288,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":256460,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.29.58-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":556124,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134702","name":"Captura-de-pantalla-2026-02-16-a-las-10.29.58.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58.png","title":"Captura de pantalla 2026-02-16 a las 10.29.58","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.29.58-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47.png","filesize":6344356,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-300x197.png","width":300,"height":197,"mime-type":"image\/png","filesize":91377,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-300x197.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-1024x673.png","width":1024,"height":673,"mime-type":"image\/png","filesize":857293,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-1024x673.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":39414,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-768x505.png","width":768,"height":505,"mime-type":"image\/png","filesize":504224,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-768x505.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":26820,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-1536x1010.png","width":1536,"height":1010,"mime-type":"image\/png","filesize":1804286,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-1536x1010.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-2048x1346.png","width":2048,"height":1346,"mime-type":"image\/png","filesize":2992376,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-2048x1346.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-150x99.png","width":150,"height":99,"mime-type":"image\/png","filesize":27681,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-150x99.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":456583,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":222190,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":460194,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":71541,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-600x1758.png","width":600,"height":1758,"mime-type":"image\/png","filesize":1364080,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-600x1758.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1100724,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":135696,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":228685,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.47-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":483578,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134738","name":"Captura-de-pantalla-2026-02-16-a-las-10.31.47.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47.png","title":"Captura de pantalla 2026-02-16 a las 10.31.47","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.47-600x600.png 600w"},{"width":150,"height":150,"file":"2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57.png","filesize":6923003,"sizes":{"medium":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-300x199.png","width":300,"height":199,"mime-type":"image\/png","filesize":83819,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-300x199.png"},"large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-1024x680.png","width":1024,"height":680,"mime-type":"image\/png","filesize":900185,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-1024x680.png"},"thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-150x150.png","width":150,"height":150,"mime-type":"image\/png","filesize":32908,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-150x150.png"},"medium_large":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-768x510.png","width":768,"height":510,"mime-type":"image\/png","filesize":512536,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-768x510.png"},"tf-client-image-size":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-120x120.png","width":120,"height":120,"mime-type":"image\/png","filesize":21841,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-120x120.png"},"1536x1536":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-1536x1019.png","width":1536,"height":1019,"mime-type":"image\/png","filesize":1955622,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-1536x1019.png"},"2048x2048":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-2048x1359.png","width":2048,"height":1359,"mime-type":"image\/png","filesize":3289912,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-2048x1359.png"},"post-thumbnail":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-150x100.png","width":150,"height":100,"mime-type":"image\/png","filesize":23469,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-150x100.png"},"modern-property-child-slider":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-680x510.png","width":680,"height":510,"mime-type":"image\/png","filesize":449178,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-680x510.png"},"property-thumb-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-488x326.png","width":488,"height":326,"mime-type":"image\/png","filesize":213632,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-488x326.png"},"property-detail-video-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-818x417.png","width":818,"height":417,"mime-type":"image\/png","filesize":437356,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-818x417.png"},"agent-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-210x210.png","width":210,"height":210,"mime-type":"image\/png","filesize":62228,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-210x210.png"},"partners-logo":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-600x1760.png","width":600,"height":1760,"mime-type":"image\/png","filesize":1573553,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-600x1760.png"},"post-featured-image":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-1240x720.png","width":1240,"height":720,"mime-type":"image\/png","filesize":1139791,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-1240x720.png"},"gform-image-choice-sm":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-300x300.png","width":300,"height":300,"mime-type":"image\/png","filesize":123464,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-300x300.png"},"gform-image-choice-md":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-400x400.png","width":400,"height":400,"mime-type":"image\/png","filesize":215148,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-400x400.png"},"gform-image-choice-lg":{"file":"Captura-de-pantalla-2026-02-16-a-las-10.31.57-600x600.png","width":600,"height":600,"mime-type":"image\/png","filesize":475954,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-600x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"134742","name":"Captura-de-pantalla-2026-02-16-a-las-10.31.57.png","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57.png","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-150x150.png","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57.png","title":"Captura de pantalla 2026-02-16 a las 10.31.57","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-150x150.png 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-120x120.png 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-210x210.png 210w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-300x300.png 300w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-400x400.png 400w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/07\/Captura-de-pantalla-2026-02-16-a-las-10.31.57-600x600.png 600w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_agent_display_option":"none","REAL_HOMES_agents":[],"REAL_HOMES_energy_class":"none","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"global","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"0","inspiry_additional_fee":"0","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0","REAL_HOMES_hide_advance_search":"0","REAL_HOMES_custom_search_form":"default","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":""},"_links":{"self":[{"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/property\/113141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/comments?post=113141"}],"version-history":[{"count":2,"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/property\/113141\/revisions"}],"predecessor-version":[{"id":113146,"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/property\/113141\/revisions\/113146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/media\/134702"}],"wp:attachment":[{"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/media?parent=113141"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/property-feature?post=113141"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/property-type?post=113141"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/property-city?post=113141"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/www.ro-spain.com\/es\/wp-json\/wp\/v2\/property-status?post=113141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}