{"id":117638,"date":"2024-08-28T16:19:21","date_gmt":"2024-08-28T14:19:21","guid":{"rendered":"https:\/\/www.ro-spain.com\/property\/prachtige-vrijstaande-villas-in-algorfa-la-finca\/"},"modified":"2025-01-16T11:25:31","modified_gmt":"2025-01-16T10:25:31","slug":"wspaniale-wolnostojace-wille-w-algorfa-la-finca","status":"publish","type":"property","link":"https:\/\/www.ro-spain.com\/pl\/property\/wspaniale-wolnostojace-wille-w-algorfa-la-finca\/","title":{"rendered":"Wspania\u0142e wolnostoj\u0105ce wille w Algorfa, La Finca"},"content":{"rendered":"<p>Wolnostoj\u0105ce wille z 3 sypialniami i 3 \u0142azienkami. Rozmieszczone na jednym poziomie, z prywatnym basenem i pi\u0119knym ogrodem.<\/p>\n<p>Jasny i przestronny salon z otwart\u0105 kuchni\u0105 wyposa\u017con\u0105 w wysokie i niskie meble. Kuchnia ma nowoczesny i elegancki design. Z salonu jest bezpo\u015brednie wyj\u015bcie na taras z basenem, gdzie mo\u017cna cieszy\u0107 si\u0119 s\u0142onecznymi dniami, tak charakterystycznymi dla klimatu \u015br\u00f3dziemnomorskiego.<\/p>\n<p>Sypialnie s\u0105 przestronne i posiadaj\u0105 nowoczesne, wbudowane szafy. \u0141azienki s\u0105 w pe\u0142ni wyko\u0144czone i wyposa\u017cone w umywalk\u0119, lustro, szafk\u0119, kabin\u0119 prysznicow\u0105 i ogrzewanie pod\u0142ogowe.<\/p>\n<p>Wille posiadaj\u0105 wst\u0119pn\u0105 instalacj\u0119 klimatyzacji, pomp\u0119 ciep\u0142a, pralni\u0119 i elektrycznie otwierane drzwi wej\u015bciowe.<\/p>\n<p>Przestrzenie zewn\u0119trzne sk\u0142adaj\u0105 si\u0119 z du\u017cego basenu, wspania\u0142ego ogrodu wkomponowanego w krajobraz, tarasu i prywatnego parkingu.<\/p>\n<p>Ten wspania\u0142y projekt znajduje si\u0119 w Algorfa, uwa\u017canym za raj golfowy na Costa Blanca, na po\u0142udnie od Alicante. Wyr\u00f3\u017cnia si\u0119 krajobrazem sad\u00f3w, gaj\u00f3w cytrusowych. Mo\u017cna tu podziwia\u0107 naturalne i spokojne otoczenie, ale jednocze\u015bnie doskonale po\u0142\u0105czone drogami z du\u017cymi pobliskimi miastami &#8211; Torrevieja z pi\u0119knym portem morskim, Guardamar i jego pi\u0119knymi piaszczystymi pla\u017cami oraz Orihuela Costa z barami, restauracjami i lokalnymi targami.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wolnostoj\u0105ce wille z 3 sypialniami i 3 \u0142azienkami. Rozmieszczone na jednym poziomie, z prywatnym basenem i pi\u0119knym ogrodem. Jasny i przestronny salon z otwart\u0105 kuchni\u0105 wyposa\u017con\u0105 w wysokie i niskie meble. Kuchnia ma nowoczesny i elegancki design. Z salonu jest bezpo\u015brednie wyj\u015bcie na taras z basenem, gdzie mo\u017cna cieszy\u0107 si\u0119 s\u0142onecznymi dniami, tak charakterystycznymi dla&#8230;<\/p>\n","protected":false},"author":1,"featured_media":117634,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-feature":[315,316,317,322,324,329,516],"property-type":[301],"property-city":[662],"property-status":[306],"class_list":["post-117638","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-wyposazona-kuchnia","property-feature-ogrod","property-feature-prywatny-parking","property-feature-taras-na-dachu","property-feature-prywatny-basen","property-feature-wstepna-instalacja-klimatyzacji","property-feature-tarasnadachu-pl","property-type-wille-wolnostojace","property-city-algorfa","property-status-rynek-pierwotny","zones-cz","builders-trivee"],"aioseo_notices":[],"property_meta":{"REAL_HOMES_property_price":"555000","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"","REAL_HOMES_property_size":"134","REAL_HOMES_property_size_postfix":"m2","REAL_HOMES_property_lot_size":"443","REAL_HOMES_property_lot_size_postfix":"m2","REAL_HOMES_property_bedrooms":"3","REAL_HOMES_property_bathrooms":"2","REAL_HOMES_property_garage":"","REAL_HOMES_property_id":"CZ24.05.117607","REAL_HOMES_property_year_built":"","rvr_property_owner":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"38.0849165","longitude":"-0.7966752","zoom":"14"},"REAL_HOMES_property_address":"Algorfa, Alicante, Espa\u00f1a","REAL_HOMES_property_map":"0","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2024\/08\/Saria-Villa-1.jpg","filesize":647277,"sizes":{"medium":{"file":"Saria-Villa-1-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":23410,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-300x169.jpg"},"large":{"file":"Saria-Villa-1-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":212262,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-1024x576.jpg"},"thumbnail":{"file":"Saria-Villa-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":10050,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-150x150.jpg"},"medium_large":{"file":"Saria-Villa-1-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":121372,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-768x432.jpg"},"tf-client-image-size":{"file":"Saria-Villa-1-120x120.jpg","width":120,"height":120,"mime-type":"image\/jpeg","filesize":7059,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-120x120.jpg"},"1536x1536":{"file":"Saria-Villa-1-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":454315,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-1536x864.jpg"},"post-thumbnail":{"file":"Saria-Villa-1-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":7900,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-150x84.jpg"},"modern-property-child-slider":{"file":"Saria-Villa-1-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":110024,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-680x510.jpg"},"property-thumb-image":{"file":"Saria-Villa-1-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":56330,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-488x326.jpg"},"property-detail-video-image":{"file":"Saria-Villa-1-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":128550,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-818x417.jpg"},"agent-image":{"file":"Saria-Villa-1-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":16803,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-210x210.jpg"},"partners-logo":{"file":"Saria-Villa-1-600x1080.jpg","width":600,"height":1080,"mime-type":"image\/jpeg","filesize":190404,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-600x1080.jpg"},"post-featured-image":{"file":"Saria-Villa-1-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":304726,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"117634","name":"Saria-Villa-1.jpg","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/08\/Saria-Villa-1.jpg","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-150x150.jpg","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1.jpg","title":"Saria-Villa-1","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-150x150.jpg 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-120x120.jpg 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-1-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/Saria-Villa-2.jpg","filesize":806912,"sizes":{"medium":{"file":"Saria-Villa-2-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":26474,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-300x169.jpg"},"large":{"file":"Saria-Villa-2-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":257462,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-1024x576.jpg"},"thumbnail":{"file":"Saria-Villa-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":11744,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-150x150.jpg"},"medium_large":{"file":"Saria-Villa-2-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":145963,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-768x432.jpg"},"tf-client-image-size":{"file":"Saria-Villa-2-120x120.jpg","width":120,"height":120,"mime-type":"image\/jpeg","filesize":8119,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-120x120.jpg"},"1536x1536":{"file":"Saria-Villa-2-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":556621,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-1536x864.jpg"},"post-thumbnail":{"file":"Saria-Villa-2-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":8449,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-150x84.jpg"},"modern-property-child-slider":{"file":"Saria-Villa-2-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":143839,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-680x510.jpg"},"property-thumb-image":{"file":"Saria-Villa-2-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":70349,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-488x326.jpg"},"property-detail-video-image":{"file":"Saria-Villa-2-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":150158,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-818x417.jpg"},"agent-image":{"file":"Saria-Villa-2-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":20707,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-210x210.jpg"},"partners-logo":{"file":"Saria-Villa-2-600x1080.jpg","width":600,"height":1080,"mime-type":"image\/jpeg","filesize":249881,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-600x1080.jpg"},"post-featured-image":{"file":"Saria-Villa-2-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":377597,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"117630","name":"Saria-Villa-2.jpg","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/08\/Saria-Villa-2.jpg","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-150x150.jpg","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2.jpg","title":"Saria-Villa-2","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-150x150.jpg 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-120x120.jpg 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-2-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/Saria-Villa-8.jpg","filesize":552728,"sizes":{"medium":{"file":"Saria-Villa-8-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":19217,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-300x169.jpg"},"large":{"file":"Saria-Villa-8-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":168481,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-1024x576.jpg"},"thumbnail":{"file":"Saria-Villa-8-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8592,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-150x150.jpg"},"medium_large":{"file":"Saria-Villa-8-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":94991,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-768x432.jpg"},"tf-client-image-size":{"file":"Saria-Villa-8-120x120.jpg","width":120,"height":120,"mime-type":"image\/jpeg","filesize":6254,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-120x120.jpg"},"1536x1536":{"file":"Saria-Villa-8-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":375143,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-1536x864.jpg"},"post-thumbnail":{"file":"Saria-Villa-8-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":6931,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-150x84.jpg"},"modern-property-child-slider":{"file":"Saria-Villa-8-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":85295,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-680x510.jpg"},"property-thumb-image":{"file":"Saria-Villa-8-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":44988,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-488x326.jpg"},"property-detail-video-image":{"file":"Saria-Villa-8-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":104135,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-818x417.jpg"},"agent-image":{"file":"Saria-Villa-8-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":14058,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-210x210.jpg"},"partners-logo":{"file":"Saria-Villa-8-600x1080.jpg","width":600,"height":1080,"mime-type":"image\/jpeg","filesize":161055,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-600x1080.jpg"},"post-featured-image":{"file":"Saria-Villa-8-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":247626,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"117618","name":"Saria-Villa-8.jpg","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/08\/Saria-Villa-8.jpg","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-150x150.jpg","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8.jpg","title":"Saria-Villa-8","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-150x150.jpg 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-120x120.jpg 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-8-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/Saria-Villa-6.jpg","filesize":878166,"sizes":{"medium":{"file":"Saria-Villa-6-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":28877,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-300x169.jpg"},"large":{"file":"Saria-Villa-6-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":277853,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-1024x576.jpg"},"thumbnail":{"file":"Saria-Villa-6-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":14145,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-150x150.jpg"},"medium_large":{"file":"Saria-Villa-6-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":156399,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-768x432.jpg"},"tf-client-image-size":{"file":"Saria-Villa-6-120x120.jpg","width":120,"height":120,"mime-type":"image\/jpeg","filesize":9734,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-120x120.jpg"},"1536x1536":{"file":"Saria-Villa-6-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":600502,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-1536x864.jpg"},"post-thumbnail":{"file":"Saria-Villa-6-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":9441,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-150x84.jpg"},"modern-property-child-slider":{"file":"Saria-Villa-6-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":167009,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-680x510.jpg"},"property-thumb-image":{"file":"Saria-Villa-6-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":79004,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-488x326.jpg"},"property-detail-video-image":{"file":"Saria-Villa-6-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":166599,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-818x417.jpg"},"agent-image":{"file":"Saria-Villa-6-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":24834,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-210x210.jpg"},"partners-logo":{"file":"Saria-Villa-6-600x1080.jpg","width":600,"height":1080,"mime-type":"image\/jpeg","filesize":312201,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-600x1080.jpg"},"post-featured-image":{"file":"Saria-Villa-6-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":412297,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"117622","name":"Saria-Villa-6.jpg","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/08\/Saria-Villa-6.jpg","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-150x150.jpg","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6.jpg","title":"Saria-Villa-6","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-150x150.jpg 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-120x120.jpg 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-6-210x210.jpg 210w"},{"width":150,"height":150,"file":"2024\/08\/Saria-Villa-7.jpg","filesize":763986,"sizes":{"medium":{"file":"Saria-Villa-7-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","filesize":27134,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-300x169.jpg"},"large":{"file":"Saria-Villa-7-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","filesize":248593,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-1024x576.jpg"},"thumbnail":{"file":"Saria-Villa-7-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":12898,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-150x150.jpg"},"medium_large":{"file":"Saria-Villa-7-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","filesize":141495,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-768x432.jpg"},"tf-client-image-size":{"file":"Saria-Villa-7-120x120.jpg","width":120,"height":120,"mime-type":"image\/jpeg","filesize":8993,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-120x120.jpg"},"1536x1536":{"file":"Saria-Villa-7-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","filesize":530866,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-1536x864.jpg"},"post-thumbnail":{"file":"Saria-Villa-7-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","filesize":9200,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-150x84.jpg"},"modern-property-child-slider":{"file":"Saria-Villa-7-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":145774,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-680x510.jpg"},"property-thumb-image":{"file":"Saria-Villa-7-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":70790,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-488x326.jpg"},"property-detail-video-image":{"file":"Saria-Villa-7-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":154720,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-818x417.jpg"},"agent-image":{"file":"Saria-Villa-7-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":22368,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-210x210.jpg"},"partners-logo":{"file":"Saria-Villa-7-600x1080.jpg","width":600,"height":1080,"mime-type":"image\/jpeg","filesize":279574,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-600x1080.jpg"},"post-featured-image":{"file":"Saria-Villa-7-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":365469,"url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-1240x720.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"117626","name":"Saria-Villa-7.jpg","path":"\/home\/ro\/web\/ro-spain.com\/public_html\/wp-content\/uploads\/2024\/08\/Saria-Villa-7.jpg","url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-150x150.jpg","full_url":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7.jpg","title":"Saria-Villa-7","caption":"","description":"","alt":"","srcset":"https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-150x150.jpg 150w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-120x120.jpg 120w, https:\/\/www.ro-spain.com\/wp-content\/uploads\/2024\/08\/Saria-Villa-7-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_agent_display_option":"none","REAL_HOMES_agents":[],"REAL_HOMES_energy_class":"none","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"global","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"0","inspiry_additional_fee":"0","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0","REAL_HOMES_hide_advance_search":"0","REAL_HOMES_custom_search_form":"default","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":""},"_links":{"self":[{"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/property\/117638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/comments?post=117638"}],"version-history":[{"count":2,"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/property\/117638\/revisions"}],"predecessor-version":[{"id":117643,"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/property\/117638\/revisions\/117643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/media\/117634"}],"wp:attachment":[{"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/media?parent=117638"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/property-feature?post=117638"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/property-type?post=117638"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/property-city?post=117638"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/www.ro-spain.com\/pl\/wp-json\/wp\/v2\/property-status?post=117638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}